{"id":1201,"date":"2026-06-03T14:26:17","date_gmt":"2026-06-03T13:26:17","guid":{"rendered":"http:\/\/localhost:81\/wordpress\/?page_id=1174"},"modified":"2026-06-03T14:49:59","modified_gmt":"2026-06-03T13:49:59","slug":"bts-prothese-2","status":"publish","type":"page","link":"https:\/\/lyceedalembert.paris\/index.php\/bts-prothese-2\/","title":{"rendered":"BTS Orthoproth\u00e8siste"},"content":{"rendered":"<div class=\"wp-block-post-date__modified-date has-text-align-right wp-block-post-date\"><time datetime=\"2026-06-03T14:49:59+01:00\">3 juin 2026<\/time><\/div>\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-19a5da3a-4bed-487b-857e-5e863349c9e5\" href=\"https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2021\/01\/BTS-PROTHESE.pdf\"><br>Fiche de pr\u00e9sentation BTS Proth\u00e9siste-orth\u00e9siste<\/a><a href=\"https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2021\/01\/BTS-PROTHESE.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-19a5da3a-4bed-487b-857e-5e863349c9e5\">T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" data-id=\"3250\" src=\"https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2017\/06\/b.jpg\" alt=\"\" class=\"wp-image-3250\" srcset=\"https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2017\/06\/b.jpg 850w, https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2017\/06\/b-300x200.jpg 300w, https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2017\/06\/b-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><figcaption class=\"wp-element-caption\">Lyc\u008ee Polyvalent d&rsquo;Alembert &#8211; 75019 Paris &#8211; formation<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" data-id=\"3243\" src=\"https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2017\/06\/9-4.jpg\" alt=\"\" class=\"wp-image-3243\" srcset=\"https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2017\/06\/9-4.jpg 850w, https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2017\/06\/9-4-300x200.jpg 300w, https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2017\/06\/9-4-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" data-id=\"3244\" src=\"https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2017\/06\/10-3.jpg\" alt=\"\" class=\"wp-image-3244\" srcset=\"https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2017\/06\/10-3.jpg 850w, https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2017\/06\/10-3-300x200.jpg 300w, https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2017\/06\/10-3-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"619\" height=\"929\" data-id=\"3246\" src=\"https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2017\/06\/12-3.jpg\" alt=\"\" class=\"wp-image-3246\" srcset=\"https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2017\/06\/12-3.jpg 619w, https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2017\/06\/12-3-200x300.jpg 200w\" sizes=\"auto, (max-width: 619px) 100vw, 619px\" \/><\/figure>\n<\/figure>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2023\/06\/Plaquette-formation-V-definitive-2023-bis.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 Plaquette-formation-V-definitive-2023-bis.\"><\/object><a id=\"wp-block-file--media-3f8b2f64-f420-4a99-9d62-b4184643edc4\" href=\"https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2023\/06\/Plaquette-formation-V-definitive-2023-bis.pdf\">Plaquette-formation-V-definitive-2023-bis<\/a><a href=\"https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2023\/06\/Plaquette-formation-V-definitive-2023-bis.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-3f8b2f64-f420-4a99-9d62-b4184643edc4\">T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"color: #ff9900;\"><strong>PUBLIC<\/strong><\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les \u00e9tudiants sont recrut\u00e9s apr\u00e8s un Bac pro Technicien Appareillage Orthop\u00e9dique (T.A.O.), un Bac g\u00e9n\u00e9ral ou technologique.<br>Le recrutement se fait \u00e0 un niveau national voire international<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><span style=\"color: #ff9900;\">ACTIVITES \u2013 QUALITES REQUISES<\/span><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les \u00e9tudiants doivent avoir des aptitudes manuelles, le go\u00fbt du contact humain ainsi que le sens des responsabilit\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le titulaire du BTS Proth\u00e9siste-Orth\u00e9siste r\u00e9alise les prises d\u2019empreintes et les mesures. Il con\u00e7oit les appareils orthop\u00e9diques. Il est l\u2019interlocuteur direct des m\u00e9decins prescripteurs. Il r\u00e9pond aux probl\u00e8mes th\u00e9rapeutiques par des solutions technologiques.<br>Il s\u2019int\u00e8gre dans une \u00e9quipe m\u00e9dicale pluridisciplinaire.<br>Il participe, \u00e9ventuellement, \u00e0 la fabrication et effectue les essayages et les livraisons des orth\u00e8ses et proth\u00e8ses.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #ff9900;\"><strong>CONTENU DE LA FORMATION<\/strong><\/span><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les \u00e9tudes durent 3 ans et comportent :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bloc de comp\u00e9tences 1 : \u00e9laborer un projet th\u00e9rapeutique en orthoproth\u00e8se (connaissances m\u00e9dicales),<\/li>\n\n\n\n<li>Bloc de comp\u00e9tences 2 : mettre en oeuvre des appareillages orthop\u00e9diques relevant du domaine d&rsquo;activit\u00e9s de l&rsquo;orthoproth\u00e9siste (Sciences Appliqu\u00e9es, technologie, enseignement pratique&#8230;),<\/li>\n\n\n\n<li>Bloc de comp\u00e9tences 3 : assurer la veille professionnelle, la formation et mener une \u00e9tude dans le domaine de l&rsquo;orthoproth\u00e8se,<\/li>\n\n\n\n<li>Bloc de comp\u00e9tences 4 : Organiser les activit\u00e9s et g\u00e9rer des ressources,<\/li>\n\n\n\n<li>culture g\u00e9n\u00e9rale et expression,<\/li>\n\n\n\n<li>Langue vivante \u00e9trang\u00e8re : anglais.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La dur\u00e9e de stage est <strong>de 20 semaines<\/strong> sur les 3 ann\u00e9es.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #ff9900;\"><strong>MODALITES DE CERTIFICATION<\/strong><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Epreuves ponctuelles en fin de 3\u00e8me ann\u00e9e,<\/li>\n\n\n\n<li>\u00e9preuves en Contr\u00f4le en Cours de Formation (CCF).<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span style=\"color: #ff9900;\"><strong>DEBOUCHES \u2013 POURSUITE D\u2019ETUDES<\/strong><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le titulaire du BTS peut travailler dans une entreprise priv\u00e9e, dans un centre de r\u00e9\u00e9ducation, dans une O.N.G. (Handicap International, croix-rouge, \u2026).<\/li>\n\n\n\n<li>Il peut, \u00e9galement, cr\u00e9er sa propre entreprise.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-amber-color\">Livret d&rsquo;accueil d&rsquo;entr\u00e9e en BTS orthoproth\u00e9siste<\/mark><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Livret d&rsquo;accueil BTS Orthoproth\u00e9siste<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2026\/06\/2026-livret-daccueil-TS1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 2026 livret d&apos;accueil TS1.\"><\/object><a id=\"wp-block-file--media-405df9a1-dce2-4ee4-855a-4ae46142f2d6\" href=\"https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2026\/06\/2026-livret-daccueil-TS1.pdf\">2026 livret d&rsquo;accueil TS1<\/a><a href=\"https:\/\/lyceedalembert.paris\/wp-content\/uploads\/2026\/06\/2026-livret-daccueil-TS1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-405df9a1-dce2-4ee4-855a-4ae46142f2d6\">T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\"><strong>A DAY IN THE LIFE OF the D&rsquo;Alembert O<\/strong>&amp;<strong>P students&nbsp;!<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Dans ces vid\u00e9os r\u00e9alis\u00e9es par les \u00e9tudiant.e.s du BTS Ortho-Proth\u00e9siste, dans le cadre du cours d&rsquo;anglais de la formation, vous d\u00e9couvrirez les coulisses de la formation. Un journ\u00e9e typique dans la vie des BTS OR, la visite des ateliers, les \u00e9tapes de fabrication d&rsquo;une proth\u00e8se et les diff\u00e9rentes machines et logiciels qu&rsquo;ils utilisent !<\/h4>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video\"><iframe loading=\"lazy\" title=\"Pr\u00e9sentation par Juliette, Emma et Romane\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/UWMutCHX11k?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video\"><iframe loading=\"lazy\" title=\"Pr\u00e9sentation de Manon, Zo\u00e9 et Loris du BTS proth\u00e9se-orth\u00e8se\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/wZyA-zlUnLA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video\"><iframe loading=\"lazy\" title=\"Pr\u00e9sentation par Myl\u00e8ne, Lucile, Shana et Emeline\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/1-NqvldbAUY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"video\"><iframe loading=\"lazy\" title=\"Pr\u00e9sentation BTS orthoproth\u00e9siste par Jeanne, Benjamin, Edouard et Simon\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/LaHnuSd93Gw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>PUBLIC Les \u00e9tudiants sont recrut\u00e9s apr\u00e8s un Bac pro Technicien Appareillage Orthop\u00e9dique (T.A.O.), un Bac g\u00e9n\u00e9ral ou technologique.Le recrutement se fait \u00e0 un niveau national voire international ACTIVITES \u2013 QUALITES REQUISES Les \u00e9tudiants doivent avoir des aptitudes manuelles, le go\u00fbt du contact humain ainsi que le sens des responsabilit\u00e9s. Le titulaire du BTS Proth\u00e9siste-Orth\u00e9siste r\u00e9alise les prises d\u2019empreintes et les mesures. Il con\u00e7oit les appareils orthop\u00e9diques. Il est l\u2019interlocuteur direct des m\u00e9decins prescripteurs. Il r\u00e9pond aux probl\u00e8mes th\u00e9rapeutiques par des&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1201","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lyceedalembert.paris\/index.php\/wp-json\/wp\/v2\/pages\/1201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyceedalembert.paris\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lyceedalembert.paris\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lyceedalembert.paris\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lyceedalembert.paris\/index.php\/wp-json\/wp\/v2\/comments?post=1201"}],"version-history":[{"count":24,"href":"https:\/\/lyceedalembert.paris\/index.php\/wp-json\/wp\/v2\/pages\/1201\/revisions"}],"predecessor-version":[{"id":9465,"href":"https:\/\/lyceedalembert.paris\/index.php\/wp-json\/wp\/v2\/pages\/1201\/revisions\/9465"}],"wp:attachment":[{"href":"https:\/\/lyceedalembert.paris\/index.php\/wp-json\/wp\/v2\/media?parent=1201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}